{"id":955,"date":"2021-12-15T09:13:39","date_gmt":"2021-12-15T08:13:39","guid":{"rendered":"http:\/\/aral45.f5mxh.fr\/?p=955"},"modified":"2021-12-15T09:13:40","modified_gmt":"2021-12-15T08:13:40","slug":"wsjt-x-version-2-5-3","status":"publish","type":"post","link":"http:\/\/aral45.f5mxh.fr\/index.php\/2021\/12\/15\/wsjt-x-version-2-5-3\/","title":{"rendered":"WSJT-X version 2.5.3"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/physics.princeton.edu\/pulsar\/k1jt\/main-ui-1.4.png\" alt=\"\" width=\"293\" height=\"295\"\/><\/figure><\/div>\n\n\n\n<p>Il y a quelques jours, le groupe de d\u00e9veloppement du logiciel WSJT-X a annonc\u00e9 la mise en ligne de la version 2.5.3 pour les syst\u00e8mes d&rsquo;exploitation Windows 64 et MacOSX. Pour les autres syst\u00e8mes, ce sera la version 2.5.2.<\/p>\n\n\n\n<p>Pour rappel, ce logiciel permet la transmission dans les modes num\u00e9riques \u00e0 faible insertion, tr\u00e8s pris\u00e9s en ces p\u00e9riodes de propagation peu soutenue.<\/p>\n\n\n\n<p>Adresse du site: <a href=\"https:\/\/physics.princeton.edu\/pulsar\/k1jt\/wsjtx.html\">https:\/\/physics.princeton.edu\/pulsar\/k1jt\/wsjtx.html<\/a><\/p>\n\n\n\n<p>T\u00e9l\u00e9chargement version Windows 64: https:\/\/physics.princeton.edu\/pu<a href=\"https:\/\/physics.princeton.edu\/pulsar\/k1jt\/wsjtx-2.5.3-win64.exe\">lsar\/k1jt\/wsjtx-2.5.3-win64.exe<\/a><\/p>\n\n\n\n<p>: <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il y a quelques jours, le groupe de d\u00e9veloppement du logiciel WSJT-X a annonc\u00e9 la mise en ligne de la version 2.5.3 pour les syst\u00e8mes d&rsquo;exploitation Windows 64 et MacOSX. Pour les autres syst\u00e8mes, ce sera la version 2.5.2. Pour rappel, ce logiciel permet la transmission dans les modes num\u00e9riques&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":95,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[44,8],"tags":[],"_links":{"self":[{"href":"http:\/\/aral45.f5mxh.fr\/index.php\/wp-json\/wp\/v2\/posts\/955"}],"collection":[{"href":"http:\/\/aral45.f5mxh.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/aral45.f5mxh.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/aral45.f5mxh.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/aral45.f5mxh.fr\/index.php\/wp-json\/wp\/v2\/comments?post=955"}],"version-history":[{"count":1,"href":"http:\/\/aral45.f5mxh.fr\/index.php\/wp-json\/wp\/v2\/posts\/955\/revisions"}],"predecessor-version":[{"id":956,"href":"http:\/\/aral45.f5mxh.fr\/index.php\/wp-json\/wp\/v2\/posts\/955\/revisions\/956"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/aral45.f5mxh.fr\/index.php\/wp-json\/wp\/v2\/media\/95"}],"wp:attachment":[{"href":"http:\/\/aral45.f5mxh.fr\/index.php\/wp-json\/wp\/v2\/media?parent=955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/aral45.f5mxh.fr\/index.php\/wp-json\/wp\/v2\/categories?post=955"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/aral45.f5mxh.fr\/index.php\/wp-json\/wp\/v2\/tags?post=955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}