{"id":819,"date":"2020-05-25T09:40:45","date_gmt":"2020-05-25T07:40:45","guid":{"rendered":"http:\/\/aral45.f5mxh.fr\/?p=819"},"modified":"2020-05-25T09:40:46","modified_gmt":"2020-05-25T07:40:46","slug":"minimum-dactivite-solaire-et-ere-glaciaire-deux-phenomenes-bien-differents","status":"publish","type":"post","link":"http:\/\/aral45.f5mxh.fr\/index.php\/2020\/05\/25\/minimum-dactivite-solaire-et-ere-glaciaire-deux-phenomenes-bien-differents\/","title":{"rendered":"Minimum d&rsquo;activit\u00e9 solaire et \u00e8re glaciaire : deux ph\u00e9nom\u00e8nes bien diff\u00e9rents"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/cdn.futura-sciences.com\/buildsv6\/images\/mediumoriginal\/a\/1\/0\/a10330ab4e_50163770_41467-2018-7690-fig4-html.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p>Les astronomes annoncent l&rsquo;arriv\u00e9e imminente d&rsquo;un minimum solaire, un ph\u00e9nom\u00e8ne cyclique ayant lieu environ tous les onze ans. Sujette \u00e0 de nombreuses erreurs d&rsquo;interpr\u00e9tation, cette baisse d&rsquo;activit\u00e9 solaire m\u00e9rite que l&rsquo;on s&rsquo;y int\u00e9resse en d\u00e9tail\u2026<\/p>\n\n\n\n<p>Li<a href=\"https:\/\/www.futura-sciences.com\/planete\/actualites\/augmentation-temperature-minimum-activite-solaire-ere-glaciaire-deux-phenomenes-bien-differents-59011\/\">re la suite sur le site de FUTURASCIENCE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les astronomes annoncent l&rsquo;arriv\u00e9e imminente d&rsquo;un minimum solaire, un ph\u00e9nom\u00e8ne cyclique ayant lieu environ tous les onze ans. Sujette \u00e0 de nombreuses erreurs d&rsquo;interpr\u00e9tation, cette baisse d&rsquo;activit\u00e9 solaire m\u00e9rite que l&rsquo;on s&rsquo;y int\u00e9resse en d\u00e9tail\u2026 Lire la suite sur le site de FUTURASCIENCE<\/p>\n","protected":false},"author":1,"featured_media":151,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[30,13],"tags":[],"_links":{"self":[{"href":"http:\/\/aral45.f5mxh.fr\/index.php\/wp-json\/wp\/v2\/posts\/819"}],"collection":[{"href":"http:\/\/aral45.f5mxh.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/aral45.f5mxh.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/aral45.f5mxh.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/aral45.f5mxh.fr\/index.php\/wp-json\/wp\/v2\/comments?post=819"}],"version-history":[{"count":1,"href":"http:\/\/aral45.f5mxh.fr\/index.php\/wp-json\/wp\/v2\/posts\/819\/revisions"}],"predecessor-version":[{"id":820,"href":"http:\/\/aral45.f5mxh.fr\/index.php\/wp-json\/wp\/v2\/posts\/819\/revisions\/820"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/aral45.f5mxh.fr\/index.php\/wp-json\/wp\/v2\/media\/151"}],"wp:attachment":[{"href":"http:\/\/aral45.f5mxh.fr\/index.php\/wp-json\/wp\/v2\/media?parent=819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/aral45.f5mxh.fr\/index.php\/wp-json\/wp\/v2\/categories?post=819"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/aral45.f5mxh.fr\/index.php\/wp-json\/wp\/v2\/tags?post=819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}